{"id":7879,"date":"2025-06-11T17:53:47","date_gmt":"2025-06-11T17:53:47","guid":{"rendered":"https:\/\/prestolam.com\/fr\/?post_type=portes&#038;p=7879"},"modified":"2026-04-09T14:39:16","modified_gmt":"2026-04-09T14:39:16","slug":"7057-elegance","status":"publish","type":"portes","link":"https:\/\/prestolam.com\/fr\/portes\/7057-elegance\/","title":{"rendered":"7057-7059 \u00c9L\u00c9GANCE"},"content":{"rendered":"\n<p>Trouvez l\u2019harmonie dans l\u2019\u00e9clectisme des styles. Parfois confondu avec le style moderne, le style contemporain est en constante \u00e9volution puisqu\u2019il suit le rythme des tendances. Fonctionnel et \u00e9pur\u00e9, il est reconnu pour ses lignes droites et ses textures neutres.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Battant 2 1\/4\u201d recouvert de polyester sur MDF<\/li>\n\n\n\n<li>Panneau central de m\u00e9lamine 1\/4\u201d sur MDF<\/li>\n\n\n\n<li>7059 panneau central 8 milimetre<\/li>\n\n\n\n<li>Bande de chant en PVC de 0,5 mm sur deux largeurs<\/li>\n\n\n\n<li>Porte assembl\u00e9e 90\u00b0<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Trouvez l\u2019harmonie dans l\u2019\u00e9clectisme des styles. Parfois confondu avec le style moderne, le style contemporain est en constante \u00e9volution puisqu\u2019il suit le rythme des tendances. Fonctionnel et \u00e9pur\u00e9, il est reconnu pour ses lignes droites et ses textures neutres.<\/p>\n","protected":false},"featured_media":1513,"menu_order":37,"template":"single-portes.php","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"type_de_modele":[800],"filtre_produit":[807],"class_list":["post-7879","portes","type-portes","status-publish","format-standard","has-post-thumbnail","hentry","type_de_modele-contemporain","filtre_produit-modeles"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/prestolam.com\/fr\/wp-json\/wp\/v2\/portes\/7879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prestolam.com\/fr\/wp-json\/wp\/v2\/portes"}],"about":[{"href":"https:\/\/prestolam.com\/fr\/wp-json\/wp\/v2\/types\/portes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prestolam.com\/fr\/wp-json\/wp\/v2\/media\/1513"}],"wp:attachment":[{"href":"https:\/\/prestolam.com\/fr\/wp-json\/wp\/v2\/media?parent=7879"}],"wp:term":[{"taxonomy":"type_de_modele","embeddable":true,"href":"https:\/\/prestolam.com\/fr\/wp-json\/wp\/v2\/type_de_modele?post=7879"},{"taxonomy":"filtre_produit","embeddable":true,"href":"https:\/\/prestolam.com\/fr\/wp-json\/wp\/v2\/filtre_produit?post=7879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}